{"id":160242,"date":"2026-09-01T15:19:46","date_gmt":"2026-09-01T18:19:46","guid":{"rendered":"https:\/\/www.orc.com.br\/novo\/?p=160242"},"modified":"2026-09-01T15:19:46","modified_gmt":"2026-09-01T18:19:46","slug":"vorcaro-fez-mais-um-pagamento-para-dark-horse-alem-do-que-flavio-havia-admitido-diz-revista","status":"publish","type":"post","link":"http:\/\/www.orc.com.br\/novo\/brasil\/vorcaro-fez-mais-um-pagamento-para-dark-horse-alem-do-que-flavio-havia-admitido-diz-revista.html","title":{"rendered":"Vorcaro fez mais um pagamento para \u2018Dark Horse\u2019 al\u00e9m do que Fl\u00e1vio havia admitido, diz revista"},"content":{"rendered":"<header class=\"styles__ContainerHeaderNoticiaBlockStyled-sc-17abcbt-0 ikFzgt\">\n<div class=\"container\">\n<div class=\"container-news-informs\">\n<div>\n<h1><\/h1>\n<\/div>\n<h2>Fl\u00e1vio Bolsonaro disse que \u00faltimo repasse de Vorcaro ao filme ocorreu em maio de 2025, mas relat\u00f3rio indica mais um pagamento \u00e0 produ\u00e7\u00e3o no segundo semestre daquele ano. Senador diz que cobran\u00e7a sobre tema deve ser feita \u00e0 produtora do filme; banqueiro e produtora foram procurados, mas n\u00e3o responderam<\/h2>\n<\/div>\n<\/div>\n<\/header>\n<div class=\" ads-container \">\n<div class=\"styles__Container-sc-1v8tg5g-0 kJqVLv\">\n<div class=\"ads-placeholder-wrapper\">\n<div id=\"htopo-0\" class=\"styles__AdSlotStyled-sc-1l64tzh-0 eotsDo formato-htopo\" data-google-query-id=\"CMTT5fn-zZYDFZdF3QIdrA8wTQ\">\n<div id=\"google_ads_iframe_\/118650305\/politica\/noticia_0__container__\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"default__StyledWrapper-sc-1jubmr2-0 iIvkrZ styled-wrapper    \">\n<div class=\"styles__Tag-sc-1kqcjew-0 styles__TagStyled-sc-1kqcjew-1 dEOAIa bTRcNF container default-theme\">\n<div class=\"styles__Tag-sc-1kqcjew-0 styles__TagStyled-sc-1kqcjew-1 dEOAIa bTRcNF row\">\n<div class=\"styles__Tag-sc-1kqcjew-0 styles__TagStyled-sc-1kqcjew-1 dEOAIa bTRcNF col-12\">\n<div class=\"styles__AuthorsNoticiaContainerStyled-sc-q2i3u1-0 gpJpmR authors-noticia\">\n<div class=\"container-content authors-noticia-content --length-1\">\n<div class=\"photos\">\n<div class=\"photo\"><img title=\"Juliano  Galisi\" src=\"https:\/\/www.estadao.com.br\/resizer\/v2\/https%3A%2F%2Fauthor-service-images-prod-us-east-1.publishing.aws.arc.pub%2Festadao%2Ff9bb7497-f654-44a8-9349-c01e0f88ffa8.png?quality=80&amp;auth=520de42fee684b7cdb7b7adae9de2144dabbcc24b69aa491eafcb8bd6d5bdd34&amp;width=60&amp;height=60&amp;smart=true\" alt=\"Foto do autor Juliano  Galisi\" \/><\/div>\n<\/div>\n<div class=\"informs\">\n<div class=\"names\">Por <a title=\"Ir para p\u00e1gina do autor\" href=\"https:\/\/www.estadao.com.br\/autores\/juliano-galisi\/\" data-component-name=\"pagina-autor\">Juliano Galisi<\/a><\/div>\n<div class=\"date\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"content\" class=\"styles__ContentWrapperContainerStyled-sc-1ehbu6v-0 iMMgpd content-wrapper -paywall-parent box\">\n<div class=\"styles__ContentWrapperContainerStyled-sc-1ehbu6v-0 iMMgpd content-wrapper  news-body container content template-reportagem\" data-paywall-wrapper=\"true\">\n<p class=\"styles__ParagraphStyled-sc-6adecn-0 geGWDE theme-default  \" data-component-name=\"paragraph\">O banqueiro <a title=\"https:\/\/www.estadao.com.br\/tudo-sobre\/daniel-vorcaro\/\" href=\"https:\/\/www.estadao.com.br\/tudo-sobre\/daniel-vorcaro\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Daniel Vorcaro<\/strong><\/a> fez mais um pagamento para financiar o filme \u201c<a title=\"https:\/\/www.estadao.com.br\/tudo-sobre\/dark-horse-filme\/\" href=\"https:\/\/www.estadao.com.br\/tudo-sobre\/dark-horse-filme\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Dark Horse<\/strong><\/a>\u201d al\u00e9m do que o senador <a title=\"https:\/\/www.estadao.com.br\/tudo-sobre\/flavio-bolsonaro\/\" href=\"https:\/\/www.estadao.com.br\/tudo-sobre\/flavio-bolsonaro\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Fl\u00e1vio Bolsonaro<\/strong><\/a> (PL-RJ) havia admitido. Em maio, quando o portal <em>Intercept Brasil <\/em>revelou o financiamento da produ\u00e7\u00e3o pelo dono do <a title=\"https:\/\/www.estadao.com.br\/tudo-sobre\/banco-master\/\" href=\"https:\/\/www.estadao.com.br\/tudo-sobre\/banco-master\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Banco Master<\/strong><\/a>, o candidato \u00e0 Presid\u00eancia pelo PL alegou durante uma entrevista \u00e0 <em>GloboNews <\/em>que a \u00faltima parcela paga pelo banqueiro havia sido em maio de 2025.<\/p>\n<p class=\"styles__ParagraphStyled-sc-6adecn-0 geGWDE theme-default  \" data-component-name=\"paragraph\">A revista <em>piau\u00ed <\/em>obteve um relat\u00f3rio do <a title=\"https:\/\/www.estadao.com.br\/economia\/negocios\/holding-ostentacao-de-daniel-vorcaro-e-liquidada-nas-ilhas-cayman\/\" href=\"https:\/\/www.estadao.com.br\/economia\/negocios\/holding-ostentacao-de-daniel-vorcaro-e-liquidada-nas-ilhas-cayman\/\" target=\"_blank\" rel=\"noopener\"><strong>Conselho de Controle de Atividades Financeiras (Coaf)<\/strong><\/a> mostrando que, em setembro daquele ano, houve mais um pagamento de US$ 1,6 milh\u00e3o pelo dono do Master ao fundo Havengate, que era respons\u00e1vel por administrar o dinheiro antes de repass\u00e1-lo \u00e0 produ\u00e7\u00e3o de \u201cDark Horse\u201d.<\/p>\n<figure class=\"styles__FigureImageWrapper-sc-1qk1vbn-0 lnSyuk figure-image-wrapper      \">\n<div class=\"figure-image-container\"><\/div><figcaption class=\"ignore-change-font-for-app\"><\/figcaption><\/figure>\n<div class=\"styles__MultiParagraphAdStyled-sc-1yb8ue6-0 kAOghv theme-default\" data-component-name=\"multi-paragraph\">\n<div class=\"paragraph\">\n<p>Segundo a <em>piau\u00ed<\/em>, esse pagamento ocorreu oito dias ap\u00f3s Fl\u00e1vio Bolsonaro cobrar Daniel Vorcaro por mais repasses para o filme. \u201cAgora que \u00e9 a reta final que a gente n\u00e3o pode vacilar, n\u00e3o pode n\u00e3o honrar com os compromissos aqui, porque sen\u00e3o a gente perde tudo\u201d, disse Fl\u00e1vio Bolsonaro em uma mensagem de \u00e1udio enviada ao banqueiro.<\/p>\n<p><a title=\"https:\/\/www.estadao.com.br\/politica\/eleicoes\/flavio-diz-que-produtora-de-dark-horse-e-quem-deve-responder-sobre-novo-repasse-feito-por-vorcaro\/\" href=\"https:\/\/www.estadao.com.br\/politica\/eleicoes\/flavio-diz-que-produtora-de-dark-horse-e-quem-deve-responder-sobre-novo-repasse-feito-por-vorcaro\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>O senador afirmou nesta ter\u00e7a-feira, 1.\u00ba, que as cobran\u00e7as sobre o tema devem ser feitas \u00e0 produtora do filme, e n\u00e3o a ele<\/strong><\/a>. \u201cEssas informa\u00e7\u00f5es n\u00e3o tenho como saber, porque n\u00e3o trato disso. Tem que perguntar para a produtora. Eu sabia que ele <em>(Vorcaro)<\/em> \u00e9 investidor, mas n\u00e3o tinha como falar. A resposta tem que perguntar para a produtora\u201d, disse Fl\u00e1vio a jornalistas ao chegar ao <a title=\"https:\/\/www.estadao.com.br\/tudo-sobre\/senado-federal\/?srsltid=AfmBOooII3oZqCsrgEWKanBt8A2QCsA7pzUbLvPoCI698M9EDgB5_qXM\" href=\"https:\/\/www.estadao.com.br\/tudo-sobre\/senado-federal\/?srsltid=AfmBOooII3oZqCsrgEWKanBt8A2QCsA7pzUbLvPoCI698M9EDgB5_qXM\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Senado<\/strong><\/a>, onde presidir\u00e1 sess\u00e3o da Comiss\u00e3o de Seguran\u00e7a P\u00fablica.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<div id=\"fb_share_1\" style=\"float: right; margin-left: 10px;\"><a name=\"fb_share\" type=\"button\" share_url=\"http:\/\/www.orc.com.br\/novo\/brasil\/vorcaro-fez-mais-um-pagamento-para-dark-horse-alem-do-que-flavio-havia-admitido-diz-revista.html\" href=\"http:\/\/www.facebook.com\/sharer.php\">Share<\/a><\/div><div><script src=\"http:\/\/static.ak.fbcdn.net\/connect.php\/js\/FB.Share\" type=\"text\/javascript\"><\/script><\/div>","protected":false},"excerpt":{"rendered":"<p>Fl\u00e1vio Bolsonaro disse que \u00faltimo repasse de Vorcaro ao filme ocorreu em maio de 2025, mas relat\u00f3rio indica mais um pagamento \u00e0 produ\u00e7\u00e3o no segundo semestre daquele ano. Senador diz que cobran\u00e7a sobre tema deve ser feita \u00e0 produtora do filme; banqueiro e produtora foram procurados, mas n\u00e3o responderam Por Juliano Galisi O banqueiro Daniel &#8230;<\/p>\n","protected":false},"author":3,"featured_media":160243,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[8],"jetpack_featured_media_url":"https:\/\/orc.com.br\/novo\/wp-content\/uploads\/2026\/09\/FlavioBolsonaro2.png","_links":{"self":[{"href":"http:\/\/www.orc.com.br\/novo\/wp-json\/wp\/v2\/posts\/160242"}],"collection":[{"href":"http:\/\/www.orc.com.br\/novo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.orc.com.br\/novo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.orc.com.br\/novo\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.orc.com.br\/novo\/wp-json\/wp\/v2\/comments?post=160242"}],"version-history":[{"count":1,"href":"http:\/\/www.orc.com.br\/novo\/wp-json\/wp\/v2\/posts\/160242\/revisions"}],"predecessor-version":[{"id":160244,"href":"http:\/\/www.orc.com.br\/novo\/wp-json\/wp\/v2\/posts\/160242\/revisions\/160244"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.orc.com.br\/novo\/wp-json\/wp\/v2\/media\/160243"}],"wp:attachment":[{"href":"http:\/\/www.orc.com.br\/novo\/wp-json\/wp\/v2\/media?parent=160242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.orc.com.br\/novo\/wp-json\/wp\/v2\/categories?post=160242"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.orc.com.br\/novo\/wp-json\/wp\/v2\/tags?post=160242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}